{"id":10840,"count":2,"description":"","link":"https:\/\/getitmagazine.co.za\/highway-berea\/blog\/tag\/nozipho-mkhize\/","name":"Nozipho Mkhize","slug":"nozipho-mkhize","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nozipho Mkhize Archives - Get it Highway &amp; Berea<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nozipho Mkhize Archives - Get it Highway &amp; Berea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/getitmagazine.co.za\/highway-berea\/blog\/tag\/nozipho-mkhize\/\" \/>\n<meta property=\"og:site_name\" content=\"Get it Highway &amp; Berea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GetItDurban\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/blog\\\/tag\\\/nozipho-mkhize\\\/\",\"url\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/blog\\\/tag\\\/nozipho-mkhize\\\/\",\"name\":\"Nozipho Mkhize Archives - Get it Highway &amp; Berea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/blog\\\/tag\\\/nozipho-mkhize\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/blog\\\/tag\\\/nozipho-mkhize\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nozipho Mkhize\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/#website\",\"url\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/\",\"name\":\"Get it Highway &amp; Berea\",\"description\":\"Lifestyle Magazine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/getitmagazine.co.za\\\/highway-berea\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nozipho Mkhize Archives - Get it Highway &amp; Berea","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Nozipho Mkhize Archives - Get it Highway &amp; Berea","og_url":"https:\/\/getitmagazine.co.za\/highway-berea\/blog\/tag\/nozipho-mkhize\/","og_site_name":"Get it Highway &amp; Berea","twitter_card":"summary_large_image","twitter_site":"@GetItDurban","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/getitmagazine.co.za\/highway-berea\/blog\/tag\/nozipho-mkhize\/","url":"https:\/\/getitmagazine.co.za\/highway-berea\/blog\/tag\/nozipho-mkhize\/","name":"Nozipho Mkhize Archives - Get it Highway &amp; Berea","isPartOf":{"@id":"https:\/\/getitmagazine.co.za\/highway-berea\/#website"},"breadcrumb":{"@id":"https:\/\/getitmagazine.co.za\/highway-berea\/blog\/tag\/nozipho-mkhize\/#breadcrumb"},"inLanguage":"en-ZA"},{"@type":"BreadcrumbList","@id":"https:\/\/getitmagazine.co.za\/highway-berea\/blog\/tag\/nozipho-mkhize\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/getitmagazine.co.za\/highway-berea\/"},{"@type":"ListItem","position":2,"name":"Nozipho Mkhize"}]},{"@type":"WebSite","@id":"https:\/\/getitmagazine.co.za\/highway-berea\/#website","url":"https:\/\/getitmagazine.co.za\/highway-berea\/","name":"Get it Highway &amp; Berea","description":"Lifestyle Magazine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/getitmagazine.co.za\/highway-berea\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"}]}},"_links":{"self":[{"href":"https:\/\/getitmagazine.co.za\/highway-berea\/wp-json\/wp\/v2\/tags\/10840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getitmagazine.co.za\/highway-berea\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/getitmagazine.co.za\/highway-berea\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/getitmagazine.co.za\/highway-berea\/wp-json\/wp\/v2\/posts?tags=10840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}