{"id":1344,"count":11,"description":"","link":"https:\/\/getitmagazine.co.za\/joburg-west\/blog\/tag\/fathers-day\/","name":"Father's day","slug":"fathers-day","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Father&#039;s day Archives - Get it Joburg West<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Father&#039;s day Archives - Get it Joburg West\" \/>\n<meta property=\"og:url\" content=\"https:\/\/getitmagazine.co.za\/joburg-west\/blog\/tag\/fathers-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Get it Joburg West\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GetItJHBWest\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/blog\\\/tag\\\/fathers-day\\\/\",\"url\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/blog\\\/tag\\\/fathers-day\\\/\",\"name\":\"Father's day Archives - Get it Joburg West\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/blog\\\/tag\\\/fathers-day\\\/#breadcrumb\"},\"inLanguage\":\"en-ZA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/blog\\\/tag\\\/fathers-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Father's day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/#website\",\"url\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/\",\"name\":\"Get it Joburg West\",\"description\":\"Lifestyle Magazine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/getitmagazine.co.za\\\/joburg-west\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-ZA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Father's day Archives - Get it Joburg West","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Father's day Archives - Get it Joburg West","og_url":"https:\/\/getitmagazine.co.za\/joburg-west\/blog\/tag\/fathers-day\/","og_site_name":"Get it Joburg West","twitter_card":"summary_large_image","twitter_site":"@GetItJHBWest","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/getitmagazine.co.za\/joburg-west\/blog\/tag\/fathers-day\/","url":"https:\/\/getitmagazine.co.za\/joburg-west\/blog\/tag\/fathers-day\/","name":"Father's day Archives - Get it Joburg West","isPartOf":{"@id":"https:\/\/getitmagazine.co.za\/joburg-west\/#website"},"breadcrumb":{"@id":"https:\/\/getitmagazine.co.za\/joburg-west\/blog\/tag\/fathers-day\/#breadcrumb"},"inLanguage":"en-ZA"},{"@type":"BreadcrumbList","@id":"https:\/\/getitmagazine.co.za\/joburg-west\/blog\/tag\/fathers-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/getitmagazine.co.za\/joburg-west\/"},{"@type":"ListItem","position":2,"name":"Father's day"}]},{"@type":"WebSite","@id":"https:\/\/getitmagazine.co.za\/joburg-west\/#website","url":"https:\/\/getitmagazine.co.za\/joburg-west\/","name":"Get it Joburg West","description":"Lifestyle Magazine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/getitmagazine.co.za\/joburg-west\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-ZA"}]}},"_links":{"self":[{"href":"https:\/\/getitmagazine.co.za\/joburg-west\/wp-json\/wp\/v2\/tags\/1344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/getitmagazine.co.za\/joburg-west\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/getitmagazine.co.za\/joburg-west\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/getitmagazine.co.za\/joburg-west\/wp-json\/wp\/v2\/posts?tags=1344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}